{"id":144,"date":"2022-08-16T14:14:09","date_gmt":"2022-08-16T14:14:09","guid":{"rendered":"http:\/\/www2.stbi.net\/?page_id=144"},"modified":"2022-08-29T17:45:20","modified_gmt":"2022-08-29T17:45:20","slug":"quotes","status":"publish","type":"page","link":"https:\/\/www.stbi.net\/index.php\/quotes\/","title":{"rendered":"Quotes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"144\" class=\"elementor elementor-144\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ca21ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ca21ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4388acf\" data-id=\"4388acf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-820c2f6 elementor-widget elementor-widget-heading\" data-id=\"820c2f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get a Quote!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07ff750 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07ff750\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd656cd\" data-id=\"fd656cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6867cf6 elementor-widget elementor-widget-text-editor\" data-id=\"6867cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Please submit this form and we will get back to you as soon as possible!<\/p>\n<p>For additional questions, call us at 1-800-486-7924<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d09fa0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d09fa0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3232ccc\" data-id=\"3232ccc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7919ae elementor-widget elementor-widget-text-editor\" data-id=\"d7919ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f270-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"270\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/144#wpcf7-f270-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"270\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f270-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Customer Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"customer-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"customer-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Customer Status<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"customer-status\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"customer-status\"><option value=\"New Customer\">New Customer<\/option><option value=\"Existing Customer\">Existing Customer<\/option><\/select><\/span> <\/label>\n<\/p>\n<p><label> Customer Email<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"customer-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"customer-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Temperature<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"temperature\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"temperature\"><option value=\"Fresh\">Fresh<\/option><option value=\"Frozen\">Frozen<\/option><option value=\"Dry\">Dry<\/option><option value=\"No Freeze\">No Freeze<\/option><option value=\"Other \/ See Notes\">Other \/ See Notes<\/option><\/select><\/span> <\/label>\n<\/p>\n<p><label> Weight<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"weight\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"weight\" \/><\/span> <\/label>\n<\/p>\n<p><label> Skid Count<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"skids\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"skids\" \/><\/span> <\/label>\n<\/p>\n<p><label> Cases<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cases\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"cases\" \/><\/span> <\/label>\n<\/p>\n<p><label> Origin Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"origin-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"origin-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Pickup Date<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"pickup-date\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date date-field\" id=\"pickup-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"pickup-date\" \/><\/span> <\/label>\n<\/p>\n<p><label> Origin Zip<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"origin-zip\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"origin-zip\" \/><\/span> <\/label>\n<\/p>\n<p><label> Origin City<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"origin-city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"origin-city\" \/><\/span> <\/label>\n<\/p>\n<p><label> Origin State<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"origin-state\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"origin-state\" \/><\/span> <\/label>\n<\/p>\n<p><label> Destination Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"destination-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"destination-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Delivery Date<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"delivery-date\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date date-field\" id=\"delivery-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"delivery-date\" \/><\/span> <\/label>\n<\/p>\n<p><label> Destination Zip<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"destination-zip\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"destination-zip\" \/><\/span> <\/label>\n<\/p>\n<p><label> Destination City<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"destination-city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"destination-city\" \/><\/span> <\/label>\n<\/p>\n<p><label> Destination State<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"destination-state\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"destination-state\" \/><\/span> <\/label>\n<\/p>\n<p><label> Additional Requirements and Notes (optional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"notes\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"notes\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Get a Quote! Please submit this form and we will get back to you as soon as possible! For additional questions, call us at 1-800-486-7924.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-144","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/pages\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":24,"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/pages\/144\/revisions"}],"predecessor-version":[{"id":332,"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/pages\/144\/revisions\/332"}],"wp:attachment":[{"href":"https:\/\/www.stbi.net\/index.php\/wp-json\/wp\/v2\/media?parent=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}